{"id":526,"date":"2026-02-05T09:39:10","date_gmt":"2026-02-05T09:39:10","guid":{"rendered":"https:\/\/medstock.it\/personal-subscription\/"},"modified":"2026-03-26T10:39:00","modified_gmt":"2026-03-26T10:39:00","slug":"personal-subscription","status":"publish","type":"page","link":"https:\/\/medstock.it\/en\/personal-subscription\/","title":{"rendered":"Personal Subscription"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"526\" class=\"elementor elementor-526 elementor-91\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca70361 e-flex e-con-boxed e-con e-parent\" data-id=\"ca70361\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f06b3bd elementor-widget elementor-widget-spacer\" data-id=\"f06b3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b3e8466 e-flex e-con-boxed e-con e-parent\" data-id=\"b3e8466\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e347f65 elementor-widget elementor-widget-heading\" data-id=\"e347f65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Personal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-467fd1e e-flex e-con-boxed e-con e-parent\" data-id=\"467fd1e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f71570a e-con-full e-flex e-con e-child\" data-id=\"f71570a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0dced4 elementor-widget elementor-widget-text-editor\" data-id=\"f0dced4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>The service is reserved exclusively for professionals with a VAT number.<\/p><ol><li>By clicking the button, you will be redirected to the secure payment system.<\/li><li>Once the transaction has been successfully completed, you will receive your system access credentials via email.<\/li><li>You can start using MedStock immediately.<\/li><\/ol><p> <\/p><ul><li>You can always cancel your subscription during the trial period, without any charge, at <a href=\"https:\/\/billing.stripe.com\/p\/login\/4gwcPk0099ASc6cbII\">this link<\/a><\/li><li>For medical centers organized as companies, choose the <a href=\"https:\/\/medstock.it\/en\/practice-subscription\/\">Studio<\/a> subscription.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-231c715 elementor-widget elementor-widget-image\" data-id=\"231c715\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/medstock.it\/wp-content\/uploads\/2026\/02\/logo-MedStock-full.jpg\" class=\"attachment-large size-large wp-image-510\" alt=\"\" srcset=\"https:\/\/medstock.it\/wp-content\/uploads\/2026\/02\/logo-MedStock-full.jpg 1024w, https:\/\/medstock.it\/wp-content\/uploads\/2026\/02\/logo-MedStock-full-300x300.jpg 300w, https:\/\/medstock.it\/wp-content\/uploads\/2026\/02\/logo-MedStock-full-150x150.jpg 150w, https:\/\/medstock.it\/wp-content\/uploads\/2026\/02\/logo-MedStock-full-768x768.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81a400e e-con-full e-flex e-con e-child\" data-id=\"81a400e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74ff933 elementor-widget elementor-widget-shortcode\" data-id=\"74ff933\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">        <div class=\"medstock-registration-wrapper\" data-type=\"personal\">\n            <form class=\"medstock-registration-form\" id=\"medstock-form-personal\">\n                \n                <input type=\"hidden\" name=\"form_type\" value=\"personal\">\n                \n                                \n                <!-- Email -->\n                <div class=\"medstock-form-group\">\n                    <label for=\"email-personal\">Email <span class=\"required\">*<\/span><\/label>\n                    <input type=\"email\" \n                           id=\"email-personal\" \n                           name=\"email\" \n                           required\n                           placeholder=\"nome@esempio.it\">\n                    <span class=\"medstock-error\" data-field=\"email\"><\/span>\n                <\/div>\n                \n                <!-- Nome e Cognome (sempre presenti ma significato diverso) -->\n                <div class=\"medstock-form-row\">\n                    <div class=\"medstock-form-group\">\n                        <label for=\"nome-personal\">\n                            Nome \n                            <span class=\"required\">*<\/span>\n                        <\/label>\n                        <input type=\"text\" \n                               id=\"nome-personal\" \n                               name=\"nome\" \n                               required\n                               placeholder=\"Mario\">\n                        <span class=\"medstock-error\" data-field=\"nome\"><\/span>\n                    <\/div>\n                    \n                    <div class=\"medstock-form-group\">\n                        <label for=\"cognome-personal\">\n                            Cognome \n                            <span class=\"required\">*<\/span>\n                        <\/label>\n                        <input type=\"text\" \n                               id=\"cognome-personal\" \n                               name=\"cognome\" \n                               required\n                               placeholder=\"Rossi\">\n                        <span class=\"medstock-error\" data-field=\"cognome\"><\/span>\n                    <\/div>\n                <\/div>\n                \n                <!-- Cellulare -->\n                <div class=\"medstock-form-group\">\n                    <label for=\"cell-personal\">Cellulare <span class=\"required\">*<\/span><\/label>\n                    <input type=\"tel\" \n                           id=\"cell-personal\" \n                           name=\"cell\" \n                           required\n                           placeholder=\"+39 333 1234567\">\n                    <span class=\"medstock-error\" data-field=\"cell\"><\/span>\n                <\/div>\n                \n                <!-- Indirizzo -->\n                <div class=\"medstock-form-group\">\n                    <label for=\"line1-personal\">Indirizzo <span class=\"required\">*<\/span><\/label>\n                    <input type=\"text\" \n                           id=\"line1-personal\" \n                           name=\"line1\" \n                           required\n                           placeholder=\"Via Roma, 123\">\n                    <span class=\"medstock-error\" data-field=\"line1\"><\/span>\n                <\/div>\n                \n                <!-- Citt\u00e0, CAP, Provincia -->\n                <div class=\"medstock-form-row medstock-form-row-triple\">\n                    <div class=\"medstock-form-group\">\n                        <label for=\"city-personal\">Citt\u00e0 <span class=\"required\">*<\/span><\/label>\n                        <input type=\"text\" \n                               id=\"city-personal\" \n                               name=\"city\" \n                               required\n                               placeholder=\"Milano\">\n                        <span class=\"medstock-error\" data-field=\"city\"><\/span>\n                    <\/div>\n                    \n                    <div class=\"medstock-form-group\">\n                        <label for=\"postal_code-personal\">CAP <span class=\"required\">*<\/span><\/label>\n                        <input type=\"text\" \n                               id=\"postal_code-personal\" \n                               name=\"postal_code\" \n                               required\n                               pattern=\"[0-9]{5}\"\n                               placeholder=\"20100\">\n                        <span class=\"medstock-error\" data-field=\"postal_code\"><\/span>\n                    <\/div>\n                    \n                    <div class=\"medstock-form-group\">\n                        <label for=\"provincia-personal\">Provincia <span class=\"required\">*<\/span><\/label>\n                        <input type=\"text\" \n                               id=\"provincia-personal\" \n                               name=\"provincia\" \n                               required\n                               maxlength=\"2\"\n                               placeholder=\"MI\"\n                               style=\"text-transform: uppercase;\">\n                        <span class=\"medstock-error\" data-field=\"provincia\"><\/span>\n                    <\/div>\n                <\/div>\n                \n                <!-- P.IVA e Codice Fiscale -->\n                <div class=\"medstock-form-row\">\n                    <div class=\"medstock-form-group\">\n                        <label for=\"piva-personal\">Partita IVA <span class=\"required\">*<\/span><\/label>\n                       <input type=\"text\" \n                               id=\"piva-personal\" \n                               name=\"piva\" \n                               required\n                               pattern=\"[A-Z,a-z]{2}[0-9]{11}\"\n                               maxlength=\"13\"\n                               placeholder=\"es. IT12345678901\"\n                               style=\"text-transform: uppercase;\">\n                        <span class=\"medstock-error\" data-field=\"piva\"><\/span>\n                    <\/div>\n                    \n                    <div class=\"medstock-form-group\">\n                        <label for=\"cf-personal\">Codice Fiscale <span class=\"required\">*<\/span><\/label>\n                        <input type=\"text\" \n                               id=\"cf-personal\" \n                               name=\"cf\" \n                               required\n                               maxlength=\"16\"\n                               placeholder=\"RSSMRA80A01H501U\"\n                               style=\"text-transform: uppercase;\">\n                        <span class=\"medstock-error\" data-field=\"cf\"><\/span>\n                    <\/div>\n                <\/div>\n                \n                <!-- Codice SDI -->\n                <div class=\"medstock-form-group\">\n                    <label for=\"codice_sdi-personal\">Codice SDI <span class=\"required\">*<\/span><\/label>\n                    <input type=\"text\" \n                           id=\"codice_sdi-personal\" \n                           name=\"codice_sdi\" \n                           required\n                           maxlength=\"7\"\n                           placeholder=\"XXXXXXX o 0000000\"\n                           style=\"text-transform: uppercase;\">\n                    <small>7 caratteri alfanumerici o 0000000 se usi PEC<\/small>\n                    <span class=\"medstock-error\" data-field=\"codice_sdi\"><\/span>\n                <\/div>\n                \n                <!-- Termini e Privacy -->\n                <div class=\"medstock-form-group medstock-checkbox-group\">\n                    <label class=\"medstock-checkbox-label\">\n                        <input type=\"checkbox\" \n                               id=\"terms-personal\" \n                               name=\"terms\" \n                               required>\n                        <span>Accetto i <a href=\"\/termini-e-condizioni\" target=\"_blank\">Termini e Condizioni<\/a> <span class=\"required\">*<\/span><\/span>\n                    <\/label>\n                    <span class=\"medstock-error\" data-field=\"terms\"><\/span>\n                <\/div>\n                \n                <div class=\"medstock-form-group medstock-checkbox-group\">\n                    <label class=\"medstock-checkbox-label\">\n                        <input type=\"checkbox\" \n                               id=\"terms2-personal\" \n                               name=\"terms2\" \n                               required>\n                        <span>Accetto la <a href=\"\/privacy-policy\" target=\"_blank\">Privacy Policy<\/a> <span class=\"required\">*<\/span><\/span>\n                    <\/label>\n                    <span class=\"medstock-error\" data-field=\"terms2\"><\/span>\n                <\/div>\n                \n                <!-- Submit Button -->\n                <div class=\"medstock-form-group\">\n                    <button type=\"submit\" class=\"medstock-submit-btn\">\n                        <span class=\"medstock-btn-text\">Procedi al Pagamento<\/span>\n                        <span class=\"medstock-btn-loader\" style=\"display: none;\">\n                            <svg class=\"medstock-spinner\" viewBox=\"0 0 50 50\">\n                                <circle class=\"path\" cx=\"25\" cy=\"25\" r=\"20\" fill=\"none\" stroke-width=\"5\"><\/circle>\n                            <\/svg>\n                        <\/span>\n                    <\/button>\n                <\/div>\n                \n                <!-- Error message container -->\n                <div class=\"medstock-form-message medstock-form-error\" style=\"display: none;\">\n                    <p><\/p>\n                <\/div>\n                \n            <\/form>\n        <\/div>\n        <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Personal The service is reserved exclusively for professionals with a VAT number. By clicking the button, you will be redirected to the secure payment system. Once the transaction has been successfully completed, you will receive your system access credentials via email. You can start using MedStock immediately. You can always cancel your subscription during the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-526","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/pages\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/comments?post=526"}],"version-history":[{"count":1,"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/pages\/526\/revisions"}],"predecessor-version":[{"id":527,"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/pages\/526\/revisions\/527"}],"wp:attachment":[{"href":"https:\/\/medstock.it\/en\/wp-json\/wp\/v2\/media?parent=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}